{"id":2561,"date":"2020-08-29T08:47:04","date_gmt":"2020-08-29T06:47:04","guid":{"rendered":"https:\/\/oceanp.net\/home-restaurant\/"},"modified":"2025-01-19T14:42:47","modified_gmt":"2025-01-19T12:42:47","slug":"home","status":"publish","type":"page","link":"https:\/\/oceanp.net\/en\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2561\" class=\"elementor elementor-2561 elementor-6\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c4eea9 elementor-section-stretched elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c4eea9\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b8587d2\" data-id=\"b8587d2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-021f0bb elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"021f0bb\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ocean Pearl<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66ff93c elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"66ff93c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ocean Pearl is a Saudi establishment founded in alignment with our government\u2019s Vision 2030.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93d581b elementor-align-left elementor-invisible elementor-widget elementor-widget-button\" data-id=\"93d581b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:800}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/oceanp.net\/en\/about-us\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discover More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-59dfe1e\" data-id=\"59dfe1e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f60e845 elementor-widget elementor-widget-spacer\" data-id=\"f60e845\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f718b84 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f718b84\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8c171f8\" data-id=\"8c171f8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bb65fb animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"3bb65fb\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"551\" height=\"311\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/ya-4.png\" class=\"attachment-full size-full wp-image-800\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/ya-4.png 551w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/ya-4-300x169.png 300w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/ya-4-1x1.png 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/ya-4-10x6.png 10w\" sizes=\"auto, (max-width: 551px) 100vw, 551px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64b0251 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"64b0251\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c82e0ab elementor-invisible\" data-id=\"c82e0ab\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-496315a elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"496315a\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/maritime-1.png\" class=\"attachment-full size-full wp-image-891\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/maritime-1.png 64w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/maritime-1-1x1.png 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/maritime-1-10x10.png 10w\" sizes=\"auto, (max-width: 64px) 100vw, 64px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Marine yacht rental<\/h3><p class=\"elementor-image-box-description\">It is the process of renting a yacht for a specific period of time for various purposes such as tourism, transportation, research, or rescue.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-466507d elementor-invisible\" data-id=\"466507d\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1b5328 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"a1b5328\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/speed-boat-1.png\" class=\"attachment-full size-full wp-image-893\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/speed-boat-1.png 64w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/speed-boat-1-1x1.png 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/speed-boat-1-10x10.png 10w\" sizes=\"auto, (max-width: 64px) 100vw, 64px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sea boat rental<\/h3><p class=\"elementor-image-box-description\">It is a fun and flexible way to explore the seas and oceans. Whether you are looking for an exciting adventure or a quiet walk.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c0a773a elementor-invisible\" data-id=\"c0a773a\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f68269 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0f68269\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/boat.png\" class=\"attachment-full size-full wp-image-900\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/boat.png 64w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/boat-1x1.png 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/boat-10x10.png 10w\" sizes=\"auto, (max-width: 64px) 100vw, 64px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Inflatable boat rental<\/h3><p class=\"elementor-image-box-description\">It is an excellent choice for water adventure lovers. These boats are easy to carry and flexible.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-748bdb7 elementor-invisible\" data-id=\"748bdb7\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-970ed6a elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"970ed6a\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/underwater-photography.png\" class=\"attachment-full size-full wp-image-901\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/underwater-photography.png 64w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/underwater-photography-1x1.png 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/underwater-photography-10x10.png 10w\" sizes=\"auto, (max-width: 64px) 100vw, 64px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Underwater Photography<\/h3><p class=\"elementor-image-box-description\">It is a unique experience that allows you to take amazing photos of the marine world. Whether you are a professional diver or a beginner.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b9fbe4f elementor-section-content-bottom elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b9fbe4f\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-09a98a0 elementor-invisible\" data-id=\"09a98a0\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b01bc5 elementor-widget elementor-widget-heading\" data-id=\"9b01bc5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">about us\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e78e11 elementor-widget elementor-widget-text-editor\" data-id=\"1e78e11\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pearl of the Ocean is a Saudi institution established within the framework of the Kingdom\u2019s Vision 2030, which aims to enhance the Kingdom\u2019s economic position worldwide by focusing on developing vital sectors. The institution focuses on providing an integrated set of maritime and logistics services to support mega projects being implemented in the Red Sea region, which is an essential part of this ambitious vision. We seek to be a major player in achieving sustainable development by providing innovative solutions based on the latest technologies and taking into account the best environmental practices. We also aspire to contribute to accelerating the pace of economic growth by providing high-quality services that meet the needs of various sectors. We work to build strong partnerships with local and international entities to enhance our capabilities and expand our business, which supports achieving the goals of the Kingdom\u2019s Vision 2030 in building a diversified and sustainable economy.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-652515a elementor-align-left elementor-invisible elementor-widget elementor-widget-button\" data-id=\"652515a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:800}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/oceanp.net\/en\/about-us\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discover More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7da377a\" data-id=\"7da377a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-892e9e8 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"892e9e8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"701\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/Blog-list-img-2-768x701.jpg\" class=\"attachment-medium_large size-medium_large wp-image-917\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/Blog-list-img-2-768x701.jpg 768w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/Blog-list-img-2-300x274.jpg 300w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/Blog-list-img-2-600x548.jpg 600w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/Blog-list-img-2-1x1.jpg 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/Blog-list-img-2-10x10.jpg 10w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/Blog-list-img-2.jpg 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71e14be elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"71e14be\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a34418\" data-id=\"3a34418\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-07c8688 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"07c8688\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a196072 animated-slow elementor-invisible\" data-id=\"a196072\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b18fda elementor-widget elementor-widget-heading\" data-id=\"0b18fda\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Objectives of Ocean Pearl\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e351f0 elementor-widget elementor-widget-text-editor\" data-id=\"5e351f0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The objectives of Pearl of the Ocean Charter Company are to provide luxury yacht charter services with the highest levels of quality and professionalism, provide an exceptional marine experience that exceeds customer expectations, and maintain an excellent reputation in the field of marine charter and luxury. By achieving these objectives, we strive to achieve customer satisfaction, build strong relationships with them, and maintain our position as a leader in the marine charter industry.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-675233e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"675233e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/oceanp.net\/en\/about-us\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">about us<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-be1dc34 e-flex e-con-boxed e-con e-parent\" data-id=\"be1dc34\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ac65357 e-grid e-con-full e-con e-child\" data-id=\"ac65357\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4fbebd3 e-con-full e-flex e-con e-child\" data-id=\"4fbebd3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-92979af elementor-widget elementor-widget-counter\" data-id=\"92979af\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"6\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2522acf elementor-widget elementor-widget-heading\" data-id=\"2522acf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Number of years of experience\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4ebae75 e-con-full e-flex e-con e-child\" data-id=\"4ebae75\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1791622 elementor-widget elementor-widget-counter\" data-id=\"1791622\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"37\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-795ca04 elementor-widget elementor-widget-heading\" data-id=\"795ca04\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Number of areas worked in\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a5ad630 e-con-full e-flex e-con e-child\" data-id=\"a5ad630\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a3db2f6 elementor-widget elementor-widget-counter\" data-id=\"a3db2f6\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"34353\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad4c8f5 elementor-widget elementor-widget-heading\" data-id=\"ad4c8f5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Number of flights carried out\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2dd4049 e-con-full e-flex e-con e-child\" data-id=\"2dd4049\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e3404d7 elementor-widget elementor-widget-counter\" data-id=\"e3404d7\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"51436\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a9be92 elementor-widget elementor-widget-heading\" data-id=\"5a9be92\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Number of flight hours carried out\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44e1efb elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"44e1efb\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c2bc4c2\" data-id=\"c2bc4c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-379fcf6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"379fcf6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-43b9436\" data-id=\"43b9436\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49f0887 elementor-widget elementor-widget-heading\" data-id=\"49f0887\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Work areas\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ca8fd7 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ca8fd7\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-48667b7\" data-id=\"48667b7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3107a0f e-flex e-con-boxed e-con e-parent\" data-id=\"3107a0f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d15c8cd elementor-widget elementor-widget-image\" data-id=\"d15c8cd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"508\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/sindalah-map-new-1024x508.png\" class=\"attachment-large size-large wp-image-2086\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/sindalah-map-new-1024x508.png 1024w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/sindalah-map-new-300x149.png 300w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/sindalah-map-new-768x381.png 768w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/sindalah-map-new-1536x763.png 1536w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/sindalah-map-new-2048x1017.png 2048w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/sindalah-map-new-600x298.png 600w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/sindalah-map-new-1x1.png 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/sindalah-map-new-10x5.png 10w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec3f801 elementor-widget elementor-widget-heading\" data-id=\"ec3f801\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NEOM Island\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-978726c\" data-id=\"978726c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c32e78b e-flex e-con-boxed e-con e-parent\" data-id=\"c32e78b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b15e3c0 elementor-widget elementor-widget-image\" data-id=\"b15e3c0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u0645\u0646\u0637\u0642\u0629_\u0646\u064a\u0648\u0645_-300x200.jpg\" class=\"attachment-medium size-medium wp-image-2202\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u0645\u0646\u0637\u0642\u0629_\u0646\u064a\u0648\u0645_-300x200.jpg 300w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u0645\u0646\u0637\u0642\u0629_\u0646\u064a\u0648\u0645_-1024x682.jpg 1024w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u0645\u0646\u0637\u0642\u0629_\u0646\u064a\u0648\u0645_-768x512.jpg 768w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u0645\u0646\u0637\u0642\u0629_\u0646\u064a\u0648\u0645_-1536x1023.jpg 1536w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u0645\u0646\u0637\u0642\u0629_\u0646\u064a\u0648\u0645_-600x400.jpg 600w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u0645\u0646\u0637\u0642\u0629_\u0646\u064a\u0648\u0645_-1x1.jpg 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u0645\u0646\u0637\u0642\u0629_\u0646\u064a\u0648\u0645_-10x7.jpg 10w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u0645\u0646\u0637\u0642\u0629_\u0646\u064a\u0648\u0645_.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d15ba3 elementor-widget elementor-widget-heading\" data-id=\"6d15ba3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NEOM area\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b6a038e\" data-id=\"b6a038e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36935ad e-flex e-con-boxed e-con e-parent\" data-id=\"36935ad\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5480f9a elementor-widget elementor-widget-image\" data-id=\"5480f9a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u0645\u0634\u0631\u0648\u0639_\u0627\u0644\u0628\u062d\u0631_\u0627\u0644\u0623\u062d\u0645\u0631_-300x169.jpg\" class=\"attachment-medium size-medium wp-image-2186\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u0645\u0634\u0631\u0648\u0639_\u0627\u0644\u0628\u062d\u0631_\u0627\u0644\u0623\u062d\u0645\u0631_-300x169.jpg 300w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u0645\u0634\u0631\u0648\u0639_\u0627\u0644\u0628\u062d\u0631_\u0627\u0644\u0623\u062d\u0645\u0631_-1024x576.jpg 1024w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u0645\u0634\u0631\u0648\u0639_\u0627\u0644\u0628\u062d\u0631_\u0627\u0644\u0623\u062d\u0645\u0631_-768x432.jpg 768w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u0645\u0634\u0631\u0648\u0639_\u0627\u0644\u0628\u062d\u0631_\u0627\u0644\u0623\u062d\u0645\u0631_-600x338.jpg 600w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u0645\u0634\u0631\u0648\u0639_\u0627\u0644\u0628\u062d\u0631_\u0627\u0644\u0623\u062d\u0645\u0631_-1x1.jpg 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u0645\u0634\u0631\u0648\u0639_\u0627\u0644\u0628\u062d\u0631_\u0627\u0644\u0623\u062d\u0645\u0631_-10x6.jpg 10w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u0645\u0634\u0631\u0648\u0639_\u0627\u0644\u0628\u062d\u0631_\u0627\u0644\u0623\u062d\u0645\u0631_.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef17db1 elementor-widget elementor-widget-heading\" data-id=\"ef17db1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Red Sea Project\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd9fff4 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd9fff4\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-979843b\" data-id=\"979843b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a426a59 e-flex e-con-boxed e-con e-parent\" data-id=\"a426a59\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ce02cb elementor-widget elementor-widget-image\" data-id=\"6ce02cb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"297\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/Fnv9SYkacAAn4x3-300x297.jpg\" class=\"attachment-medium size-medium wp-image-2082\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/Fnv9SYkacAAn4x3-300x297.jpg 300w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/Fnv9SYkacAAn4x3-150x150.jpg 150w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/Fnv9SYkacAAn4x3-768x761.jpg 768w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/Fnv9SYkacAAn4x3-600x595.jpg 600w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/Fnv9SYkacAAn4x3-100x100.jpg 100w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/Fnv9SYkacAAn4x3-1x1.jpg 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/Fnv9SYkacAAn4x3-10x10.jpg 10w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/Fnv9SYkacAAn4x3.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-685d414 elementor-widget elementor-widget-heading\" data-id=\"685d414\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Shusha Island\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-100a562\" data-id=\"100a562\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12f89d3 e-flex e-con-boxed e-con e-parent\" data-id=\"12f89d3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb04681 elementor-widget elementor-widget-image\" data-id=\"fb04681\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0643\u062f\u0645\u0628\u0644_-300x200.jpg\" class=\"attachment-medium size-medium wp-image-2190\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0643\u062f\u0645\u0628\u0644_-300x200.jpg 300w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0643\u062f\u0645\u0628\u0644_-1024x682.jpg 1024w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0643\u062f\u0645\u0628\u0644_-768x511.jpg 768w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0643\u062f\u0645\u0628\u0644_-1536x1022.jpg 1536w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0643\u062f\u0645\u0628\u0644_-600x399.jpg 600w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0643\u062f\u0645\u0628\u0644_-1x1.jpg 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0643\u062f\u0645\u0628\u0644_-10x7.jpg 10w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0643\u062f\u0645\u0628\u0644_.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc3a5a2 elementor-widget elementor-widget-heading\" data-id=\"fc3a5a2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kadambale Island\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a3498d1\" data-id=\"a3498d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb11c23 e-flex e-con-boxed e-con e-parent\" data-id=\"cb11c23\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d5bfcd7 elementor-widget elementor-widget-image\" data-id=\"d5bfcd7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0633\u0646\u062f\u0627\u0644\u0629_-1024x576.jpg\" class=\"attachment-large size-large wp-image-2198\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0633\u0646\u062f\u0627\u0644\u0629_-1024x576.jpg 1024w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0633\u0646\u062f\u0627\u0644\u0629_-300x169.jpg 300w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0633\u0646\u062f\u0627\u0644\u0629_-768x432.jpg 768w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0633\u0646\u062f\u0627\u0644\u0629_-1536x864.jpg 1536w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0633\u0646\u062f\u0627\u0644\u0629_-600x338.jpg 600w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0633\u0646\u062f\u0627\u0644\u0629_-1x1.jpg 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0633\u0646\u062f\u0627\u0644\u0629_-10x6.jpg 10w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/\u062c\u0632\u064a\u0631\u0629_\u0633\u0646\u062f\u0627\u0644\u0629_.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2744e47 elementor-widget elementor-widget-heading\" data-id=\"2744e47\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sindalah Island\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba0102d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba0102d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72d1ba8\" data-id=\"72d1ba8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6b27bd elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b6b27bd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/oceanp.net\/en\/work-areas\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get to Know the Areas of Work<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5841e12 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"5841e12\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"455\" height=\"210\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/ana-sayfa-gorsel-c456b880-bb25-48cf-9135-f043111c53a2-e1728474623795.png\" class=\"attachment-full size-full wp-image-1009\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/ana-sayfa-gorsel-c456b880-bb25-48cf-9135-f043111c53a2-e1728474623795.png 455w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/ana-sayfa-gorsel-c456b880-bb25-48cf-9135-f043111c53a2-e1728474623795-300x138.png 300w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/ana-sayfa-gorsel-c456b880-bb25-48cf-9135-f043111c53a2-e1728474623795-1x1.png 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/ana-sayfa-gorsel-c456b880-bb25-48cf-9135-f043111c53a2-e1728474623795-10x5.png 10w\" sizes=\"auto, (max-width: 455px) 100vw, 455px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79934d74 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"79934d74\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6fe80402\" data-id=\"6fe80402\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4b2e8faf elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4b2e8faf\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-448263a7 elementor-invisible\" data-id=\"448263a7\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fbcf206 elementor-widget elementor-widget-heading\" data-id=\"4fbcf206\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Success partners\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-861799f e-flex e-con-boxed e-con e-parent\" data-id=\"861799f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b2b1536 e-con-full e-flex e-con e-child\" data-id=\"b2b1536\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6ca9270 e-con-full e-flex e-con e-child\" data-id=\"6ca9270\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4bf3d5f e-con-full e-flex e-con e-child\" data-id=\"4bf3d5f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3753349 elementor-widget elementor-widget-image\" data-id=\"3753349\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/team2.jpg\" class=\"attachment-full size-full wp-image-1380\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/team2.jpg 500w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/team2-300x300.jpg 300w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/team2-150x150.jpg 150w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/team2-100x100.jpg 100w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/team2-1x1.jpg 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/team2-10x10.jpg 10w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fb66b76 e-con-full e-flex e-con e-child\" data-id=\"fb66b76\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f78ad65 elementor-widget elementor-widget-image\" data-id=\"f78ad65\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1789\" height=\"518\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/\u062c\u0627\u0645\u0639\u0629-\u0627\u0644\u0645\u0644\u0643-\u0639\u0628\u062f\u0627\u0644\u0644\u0647-\u0644\u0644\u0639\u0644\u0648\u0645-\u0648\u0627\u0644\u062a\u0642\u0646\u064a\u0629.png\" class=\"attachment-full size-full wp-image-1053\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/\u062c\u0627\u0645\u0639\u0629-\u0627\u0644\u0645\u0644\u0643-\u0639\u0628\u062f\u0627\u0644\u0644\u0647-\u0644\u0644\u0639\u0644\u0648\u0645-\u0648\u0627\u0644\u062a\u0642\u0646\u064a\u0629.png 1789w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/\u062c\u0627\u0645\u0639\u0629-\u0627\u0644\u0645\u0644\u0643-\u0639\u0628\u062f\u0627\u0644\u0644\u0647-\u0644\u0644\u0639\u0644\u0648\u0645-\u0648\u0627\u0644\u062a\u0642\u0646\u064a\u0629-300x87.png 300w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/\u062c\u0627\u0645\u0639\u0629-\u0627\u0644\u0645\u0644\u0643-\u0639\u0628\u062f\u0627\u0644\u0644\u0647-\u0644\u0644\u0639\u0644\u0648\u0645-\u0648\u0627\u0644\u062a\u0642\u0646\u064a\u0629-1024x296.png 1024w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/\u062c\u0627\u0645\u0639\u0629-\u0627\u0644\u0645\u0644\u0643-\u0639\u0628\u062f\u0627\u0644\u0644\u0647-\u0644\u0644\u0639\u0644\u0648\u0645-\u0648\u0627\u0644\u062a\u0642\u0646\u064a\u0629-768x222.png 768w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/\u062c\u0627\u0645\u0639\u0629-\u0627\u0644\u0645\u0644\u0643-\u0639\u0628\u062f\u0627\u0644\u0644\u0647-\u0644\u0644\u0639\u0644\u0648\u0645-\u0648\u0627\u0644\u062a\u0642\u0646\u064a\u0629-1536x445.png 1536w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/\u062c\u0627\u0645\u0639\u0629-\u0627\u0644\u0645\u0644\u0643-\u0639\u0628\u062f\u0627\u0644\u0644\u0647-\u0644\u0644\u0639\u0644\u0648\u0645-\u0648\u0627\u0644\u062a\u0642\u0646\u064a\u0629-600x174.png 600w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/\u062c\u0627\u0645\u0639\u0629-\u0627\u0644\u0645\u0644\u0643-\u0639\u0628\u062f\u0627\u0644\u0644\u0647-\u0644\u0644\u0639\u0644\u0648\u0645-\u0648\u0627\u0644\u062a\u0642\u0646\u064a\u0629-1x1.png 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/\u062c\u0627\u0645\u0639\u0629-\u0627\u0644\u0645\u0644\u0643-\u0639\u0628\u062f\u0627\u0644\u0644\u0647-\u0644\u0644\u0639\u0644\u0648\u0645-\u0648\u0627\u0644\u062a\u0642\u0646\u064a\u0629-10x3.png 10w\" sizes=\"auto, (max-width: 1789px) 100vw, 1789px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e16b41 e-con-full e-flex e-con e-child\" data-id=\"2e16b41\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-24a5e2f elementor-widget elementor-widget-image\" data-id=\"24a5e2f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1250\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/65793.jpg\" class=\"attachment-full size-full wp-image-1055\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/65793.jpg 2000w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/65793-300x188.jpg 300w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/65793-1024x640.jpg 1024w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/65793-768x480.jpg 768w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/65793-1536x960.jpg 1536w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/65793-600x375.jpg 600w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/65793-1x1.jpg 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/10\/65793-10x6.jpg 10w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-33beb5d e-con-full e-flex e-con e-child\" data-id=\"33beb5d\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-d5a8185 e-flex e-con-boxed e-con e-parent\" data-id=\"d5a8185\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec95c54 elementor-widget elementor-widget-heading\" data-id=\"ec95c54\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Send us an email\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-547dfb0 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"547dfb0\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-13b8b59\" data-id=\"13b8b59\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0454768 elementor-widget elementor-widget-heading\" data-id=\"0454768\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">We will contact you as soon as possible. It usually takes 10 minutes\n\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f85711 elementor-widget__width-inherit elementor-widget-mobile__width-initial etheme-contact-form-7-button-custom elementor-widget elementor-widget-et-contact-form-7\" data-id=\"9f85711\" data-element_type=\"widget\" data-widget_type=\"et-contact-form-7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                <div class=\"pp-contact-form etheme-contact-form-7 labels-hide placeholder-show\">\r\n                                        \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2568-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"2568\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/2561#wpcf7-f2568-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"2568\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2568-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-6\">\n\t\t<p><label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><br \/>\n<\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\">\n\t\t<p><label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><br \/>\n<\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-6\">\n\t\t<p><label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone\" value=\"\" type=\"tel\" name=\"your-phone\" \/><\/span><br \/>\n<\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\">\n\t\t<p><label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-another-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" placeholder=\"Booking number\" value=\"\" type=\"tel\" name=\"your-another-phone\" \/><\/span><br \/>\n<\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-12\">\n\t\t<p><label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Write a message\" name=\"your-message\"><\/textarea><\/span><br \/>\n<\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n                <\/div>\r\n                \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b112d05\" data-id=\"b112d05\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a3e476 elementor-widget elementor-widget-heading\" data-id=\"9a3e476\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">contact Us<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ba1822 elementor-vertical-align-middle elementor-position-left elementor-widget elementor-widget-image-box\" data-id=\"3ba1822\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/maps.app.goo.gl\/mUDtCV7T5bAXyjr99\" tabindex=\"-1\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/pin.png\" class=\"attachment-full size-full wp-image-1883\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/pin.png 16w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/pin-1x1.png 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/pin-10x10.png 10w\" sizes=\"auto, (max-width: 16px) 100vw, 16px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/maps.app.goo.gl\/mUDtCV7T5bAXyjr99\">Jeddah - Kingdom of Saudi Arabia<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-991f767 elementor-vertical-align-middle elementor-widget__width-inherit elementor-position-left elementor-widget elementor-widget-image-box\" data-id=\"991f767\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"\" tabindex=\"-1\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/phone-call.png\" class=\"attachment-full size-full wp-image-1884\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/phone-call.png 16w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/phone-call-1x1.png 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/phone-call-10x10.png 10w\" sizes=\"auto, (max-width: 16px) 100vw, 16px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h1 class=\"elementor-image-box-title\"><a href=\"\">0561809097<\/a><\/h1><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da4d62f elementor-vertical-align-middle elementor-widget__width-inherit elementor-position-left elementor-widget elementor-widget-image-box\" data-id=\"da4d62f\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"mailto:info@oceanp.net\" tabindex=\"-1\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/mail.png\" class=\"attachment-full size-full wp-image-1885\" alt=\"\" srcset=\"https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/mail.png 16w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/mail-1x1.png 1w, https:\/\/oceanp.net\/wp-content\/uploads\/2024\/12\/mail-10x10.png 10w\" sizes=\"auto, (max-width: 16px) 100vw, 16px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"mailto:info@oceanp.net\">info@oceanp.net<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e49bab elementor-icon-list--layout-inline elementor-align-left elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1e49bab\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Facebook<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"et-icon et-linkedin\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">LinkedIn<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Instagram<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-snapchat\" viewBox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M248 8C111 8 0 119 0 256s111 248 248 248 248-111 248-248S385 8 248 8zm169.5 338.9c-3.5 8.1-18.1 14-44.8 18.2-1.4 1.9-2.5 9.8-4.3 15.9-1.1 3.7-3.7 5.9-8.1 5.9h-.2c-6.2 0-12.8-2.9-25.8-2.9-17.6 0-23.7 4-37.4 13.7-14.5 10.3-28.4 19.1-49.2 18.2-21 1.6-38.6-11.2-48.5-18.2-13.8-9.7-19.8-13.7-37.4-13.7-12.5 0-20.4 3.1-25.8 3.1-5.4 0-7.5-3.3-8.3-6-1.8-6.1-2.9-14.1-4.3-16-13.8-2.1-44.8-7.5-45.5-21.4-.2-3.6 2.3-6.8 5.9-7.4 46.3-7.6 67.1-55.1 68-57.1 0-.1.1-.2.2-.3 2.5-5 3-9.2 1.6-12.5-3.4-7.9-17.9-10.7-24-13.2-15.8-6.2-18-13.4-17-18.3 1.6-8.5 14.4-13.8 21.9-10.3 5.9 2.8 11.2 4.2 15.7 4.2 3.3 0 5.5-.8 6.6-1.4-1.4-23.9-4.7-58 3.8-77.1C183.1 100 230.7 96 244.7 96c.6 0 6.1-.1 6.7-.1 34.7 0 68 17.8 84.3 54.3 8.5 19.1 5.2 53.1 3.8 77.1 1.1.6 2.9 1.3 5.7 1.4 4.3-.2 9.2-1.6 14.7-4.2 4-1.9 9.6-1.6 13.6 0 6.3 2.3 10.3 6.8 10.4 11.9.1 6.5-5.7 12.1-17.2 16.6-1.4.6-3.1 1.1-4.9 1.7-6.5 2.1-16.4 5.2-19 11.5-1.4 3.3-.8 7.5 1.6 12.5.1.1.1.2.2.3.9 2 21.7 49.5 68 57.1 4 1 7.1 5.5 4.9 10.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Snapchat<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ocean Pearl Ocean Pearl is a Saudi establishment founded in alignment with our government\u2019s Vision 2030. Discover More Marine yacht rental It is the process<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2561","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/oceanp.net\/en\/wp-json\/wp\/v2\/pages\/2561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oceanp.net\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oceanp.net\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oceanp.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oceanp.net\/en\/wp-json\/wp\/v2\/comments?post=2561"}],"version-history":[{"count":127,"href":"https:\/\/oceanp.net\/en\/wp-json\/wp\/v2\/pages\/2561\/revisions"}],"predecessor-version":[{"id":3140,"href":"https:\/\/oceanp.net\/en\/wp-json\/wp\/v2\/pages\/2561\/revisions\/3140"}],"wp:attachment":[{"href":"https:\/\/oceanp.net\/en\/wp-json\/wp\/v2\/media?parent=2561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}